{"id":23495,"date":"2022-05-10T13:37:36","date_gmt":"2022-05-10T12:37:36","guid":{"rendered":"https:\/\/soziolinguistika.eus\/hizkuntza\/feroes\/"},"modified":"2022-05-10T13:37:36","modified_gmt":"2022-05-10T12:37:36","slug":"feroes","status":"publish","type":"hizkuntza","link":"https:\/\/soziolinguistika.eus\/es\/hizkuntza\/feroes\/","title":{"rendered":"Fero\u00e9s"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","class_list":["post-23495","hizkuntza","type-hizkuntza","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fero\u00e9s - Soziolinguistika Klusterra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soziolinguistika.eus\/es\/hizkuntza\/feroes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fero\u00e9s - Soziolinguistika Klusterra\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soziolinguistika.eus\/es\/hizkuntza\/feroes\/\" \/>\n<meta property=\"og:site_name\" content=\"Soziolinguistika Klusterra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/soziolinguistika.eus\\\/es\\\/hizkuntza\\\/feroes\\\/\",\"url\":\"https:\\\/\\\/soziolinguistika.eus\\\/es\\\/hizkuntza\\\/feroes\\\/\",\"name\":\"Fero\u00e9s - Soziolinguistika Klusterra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soziolinguistika.eus\\\/es\\\/#website\"},\"datePublished\":\"2022-05-10T12:37:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/soziolinguistika.eus\\\/es\\\/hizkuntza\\\/feroes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/soziolinguistika.eus\\\/es\\\/hizkuntza\\\/feroes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/soziolinguistika.eus\\\/es\\\/hizkuntza\\\/feroes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Soziolinguistika klusterra\",\"item\":\"https:\\\/\\\/soziolinguistika.eus\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hizkuntzak\",\"item\":\"https:\\\/\\\/soziolinguistika.eus\\\/es\\\/hizkuntza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fero\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/soziolinguistika.eus\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/soziolinguistika.eus\\\/es\\\/\",\"name\":\"Soziolinguistika Klusterra\",\"description\":\"Euskara biziberritzeko ikergunea\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/soziolinguistika.eus\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fero\u00e9s - Soziolinguistika Klusterra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soziolinguistika.eus\/es\/hizkuntza\/feroes\/","og_locale":"es_ES","og_type":"article","og_title":"Fero\u00e9s - Soziolinguistika Klusterra","og_url":"https:\/\/soziolinguistika.eus\/es\/hizkuntza\/feroes\/","og_site_name":"Soziolinguistika Klusterra","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/soziolinguistika.eus\/es\/hizkuntza\/feroes\/","url":"https:\/\/soziolinguistika.eus\/es\/hizkuntza\/feroes\/","name":"Fero\u00e9s - Soziolinguistika Klusterra","isPartOf":{"@id":"https:\/\/soziolinguistika.eus\/es\/#website"},"datePublished":"2022-05-10T12:37:36+00:00","breadcrumb":{"@id":"https:\/\/soziolinguistika.eus\/es\/hizkuntza\/feroes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soziolinguistika.eus\/es\/hizkuntza\/feroes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/soziolinguistika.eus\/es\/hizkuntza\/feroes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Soziolinguistika klusterra","item":"https:\/\/soziolinguistika.eus\/es\/"},{"@type":"ListItem","position":2,"name":"Hizkuntzak","item":"https:\/\/soziolinguistika.eus\/es\/hizkuntza\/"},{"@type":"ListItem","position":3,"name":"Fero\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/soziolinguistika.eus\/es\/#website","url":"https:\/\/soziolinguistika.eus\/es\/","name":"Soziolinguistika Klusterra","description":"Euskara biziberritzeko ikergunea","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soziolinguistika.eus\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/soziolinguistika.eus\/es\/wp-json\/wp\/v2\/hizkuntza\/23495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soziolinguistika.eus\/es\/wp-json\/wp\/v2\/hizkuntza"}],"about":[{"href":"https:\/\/soziolinguistika.eus\/es\/wp-json\/wp\/v2\/types\/hizkuntza"}],"wp:attachment":[{"href":"https:\/\/soziolinguistika.eus\/es\/wp-json\/wp\/v2\/media?parent=23495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}