{"id":23685,"date":"2022-05-10T13:48:50","date_gmt":"2022-05-10T12:48:50","guid":{"rendered":"https:\/\/soziolinguistika.eus\/ekitaldia\/lanabes-araban-euskara-lanean-2\/"},"modified":"2022-05-10T13:48:50","modified_gmt":"2022-05-10T12:48:50","slug":"lanabes-araban-euskara-lanean-2","status":"publish","type":"ekitaldia","link":"https:\/\/soziolinguistika.eus\/fr\/ekitaldia\/lanabes-araban-euskara-lanean-2\/","title":{"rendered":"LANABES \u2013 Araban Euskara Lanean"},"content":{"rendered":"<p>Avec l&#039;initiative Lanabes &#8211; Araban Euskara Lanean, nous souhaitons renforcer l&#039;utilisation du basque dans le monde des entreprises de la province d&rsquo;Alava.<\/p>\n<p>Les entreprises de notre province sont de plus en plus nombreuses &agrave; int&eacute;grer la gestion du basque dans leur travail quotidien, dans leurs rapports avec leurs clients ou leurs fournisseurs, dans le paysage linguistique, au niveau interne et externe. Une bonne preuve de cette r&eacute;alit&eacute; sont les entreprises qui ont obtenu les certificats Bai Euskarari ou Bikain, ou celles qui ont mis en place un plan de basque. C&#039;est d&rsquo;ores et d&eacute;j&agrave; une r&eacute;alit&eacute; et les entreprises ont conscience du fait que les b&eacute;n&eacute;fices qu&#039;apportent la promotion et l&#039;utilisation du basque dans le domaine socio-&eacute;conomique.<\/p>\n<p>Les principaux OBJECTIFS du projet LANABES sont d&#039;introduire et d&#039;accro&icirc;tre la pr&eacute;sence du basque ainsi que de promouvoir le basque dans le monde socio-&eacute;conomique d&rsquo;Alava. Nous avons pour ce faire dessin&eacute; trois lignes de travail :<\/p>\n<ul>\n<li>Garantir le suivi et la diffusion du groupe dirig&eacute; par le projet Lanabes &#8211; Araban Euskara Lanean.<\/li>\n<li>Sensibiliser le secteur socio-&eacute;conomique d&#039;Alava dans le domaine de l&#039;utilisation du basque. Communication.<\/li>\n<li>Impliquer tous types d&#039;organismes et de personnes, afin d&#039;accro&icirc;tre la pr&eacute;sence du basque dans le domaine socio-&eacute;conomique d&#039;Alava.<\/li>\n<\/ul>\n<p>\nPar l&#039;interm&eacute;diaire de ce projet, nous souhaitons tisser un r&eacute;seau d&#039;entreprises et d&#039;organismes reconnus dans le domaine socio-&eacute;conomique d&#039;Alava.<\/p>\n<p>La d&eacute;put&eacute; du Conseil provincial en charge du Basque, la culture et le sport Igone Mart&iacute;nez de Luna a soulign&eacute; que jusqu&#039;ici les efforts se sont port&eacute;s sur le renforcement du basque dans l&#039;enseignement, mais il ne faut pas n&eacute;gliger le basque dans le monde du travail pour que la soci&eacute;t&eacute; continue &agrave; &ecirc;tre multilingue : &laquo; Il est tr&egrave;s important de se rendre compte que les mondes de l&#039;enseignement et du travail sont des axes importantes pour donner &agrave; la province d&#039;Alava la couleur du multilinguisme.&nbsp; Il sera n&eacute;cessaire de travailler sur les rapports entre les deux domaines, c&#039;est &agrave; pr&eacute;sent le moment de commencer. La mati&egrave;re existe, il est &agrave; pr&eacute;sent n&eacute;cessaire de disposer d&#039;outils pour apporter cette mati&egrave;re au monde du travail &raquo;, a-t-elle comment&eacute;.<\/p>\n<p>La d&eacute;put&eacute;e du Conseil provincial Mart&iacute;nez de Luna a exprim&eacute; son souhait que le monde du travail en Alava soit une r&eacute;f&eacute;rence en mati&egrave;re de gestion linguistique. Au sujet de la gestion linguistique, elle a soulign&eacute; qu&#039;il s&#039;agit d&#039;&laquo; unir &raquo; &laquo; l&#039;&eacute;quilibre entre les langues &raquo; et le &laquo; d&eacute;veloppement du territoire &raquo;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec l&#039;initiative Lanabes &#8211; Araban Euskara Lanean, nous souhaitons renforcer l&#039;utilisation du basque dans le monde des entreprises de la province d&rsquo;Alava. Les entreprises de notre province sont de plus en plus nombreuses &agrave; int&eacute;grer la gestion du basque dans leur travail quotidien, dans leurs rapports avec leurs clients ou leurs fournisseurs, dans le paysage&#8230;<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-23685","ekitaldia","type-ekitaldia","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LANABES \u2013 Araban Euskara Lanean - Soziolinguistika Klusterra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soziolinguistika.eus\/fr\/ekitaldia\/lanabes-araban-euskara-lanean-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LANABES \u2013 Araban Euskara Lanean - Soziolinguistika Klusterra\" \/>\n<meta property=\"og:description\" content=\"Avec l&#039;initiative Lanabes &#8211; Araban Euskara Lanean, nous souhaitons renforcer l&#039;utilisation du basque dans le monde des entreprises de la province d&rsquo;Alava. Les entreprises de notre province sont de plus en plus nombreuses &agrave; int&eacute;grer la gestion du basque dans leur travail quotidien, dans leurs rapports avec leurs clients ou leurs fournisseurs, dans le paysage...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soziolinguistika.eus\/fr\/ekitaldia\/lanabes-araban-euskara-lanean-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Soziolinguistika Klusterra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/soziolinguistika.eus\\\/fr\\\/ekitaldia\\\/lanabes-araban-euskara-lanean-2\\\/\",\"url\":\"https:\\\/\\\/soziolinguistika.eus\\\/fr\\\/ekitaldia\\\/lanabes-araban-euskara-lanean-2\\\/\",\"name\":\"LANABES \u2013 Araban Euskara Lanean - Soziolinguistika Klusterra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soziolinguistika.eus\\\/fr\\\/#website\"},\"datePublished\":\"2022-05-10T12:48:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/soziolinguistika.eus\\\/fr\\\/ekitaldia\\\/lanabes-araban-euskara-lanean-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/soziolinguistika.eus\\\/fr\\\/ekitaldia\\\/lanabes-araban-euskara-lanean-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/soziolinguistika.eus\\\/fr\\\/ekitaldia\\\/lanabes-araban-euskara-lanean-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Soziolinguistika klusterra\",\"item\":\"https:\\\/\\\/soziolinguistika.eus\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LANABES \u2013 Araban Euskara Lanean\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/soziolinguistika.eus\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/soziolinguistika.eus\\\/fr\\\/\",\"name\":\"Soziolinguistika Klusterra\",\"description\":\"Euskara biziberritzeko ikergunea\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/soziolinguistika.eus\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LANABES \u2013 Araban Euskara Lanean - Soziolinguistika Klusterra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soziolinguistika.eus\/fr\/ekitaldia\/lanabes-araban-euskara-lanean-2\/","og_locale":"fr_FR","og_type":"article","og_title":"LANABES \u2013 Araban Euskara Lanean - Soziolinguistika Klusterra","og_description":"Avec l&#039;initiative Lanabes &#8211; Araban Euskara Lanean, nous souhaitons renforcer l&#039;utilisation du basque dans le monde des entreprises de la province d&rsquo;Alava. Les entreprises de notre province sont de plus en plus nombreuses &agrave; int&eacute;grer la gestion du basque dans leur travail quotidien, dans leurs rapports avec leurs clients ou leurs fournisseurs, dans le paysage...","og_url":"https:\/\/soziolinguistika.eus\/fr\/ekitaldia\/lanabes-araban-euskara-lanean-2\/","og_site_name":"Soziolinguistika Klusterra","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/soziolinguistika.eus\/fr\/ekitaldia\/lanabes-araban-euskara-lanean-2\/","url":"https:\/\/soziolinguistika.eus\/fr\/ekitaldia\/lanabes-araban-euskara-lanean-2\/","name":"LANABES \u2013 Araban Euskara Lanean - Soziolinguistika Klusterra","isPartOf":{"@id":"https:\/\/soziolinguistika.eus\/fr\/#website"},"datePublished":"2022-05-10T12:48:50+00:00","breadcrumb":{"@id":"https:\/\/soziolinguistika.eus\/fr\/ekitaldia\/lanabes-araban-euskara-lanean-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soziolinguistika.eus\/fr\/ekitaldia\/lanabes-araban-euskara-lanean-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/soziolinguistika.eus\/fr\/ekitaldia\/lanabes-araban-euskara-lanean-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Soziolinguistika klusterra","item":"https:\/\/soziolinguistika.eus\/fr\/"},{"@type":"ListItem","position":2,"name":"LANABES \u2013 Araban Euskara Lanean"}]},{"@type":"WebSite","@id":"https:\/\/soziolinguistika.eus\/fr\/#website","url":"https:\/\/soziolinguistika.eus\/fr\/","name":"Soziolinguistika Klusterra","description":"Euskara biziberritzeko ikergunea","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soziolinguistika.eus\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/soziolinguistika.eus\/fr\/wp-json\/wp\/v2\/ekitaldia\/23685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soziolinguistika.eus\/fr\/wp-json\/wp\/v2\/ekitaldia"}],"about":[{"href":"https:\/\/soziolinguistika.eus\/fr\/wp-json\/wp\/v2\/types\/ekitaldia"}],"wp:attachment":[{"href":"https:\/\/soziolinguistika.eus\/fr\/wp-json\/wp\/v2\/media?parent=23685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}